{"id":819718,"date":"2025-01-14T08:11:55","date_gmt":"2025-01-14T14:11:55","guid":{"rendered":"https:\/\/newsycanuse.com\/index.php\/2025\/01\/14\/neymar-a-linter-miami-mission-impossible\/"},"modified":"2025-01-14T08:11:55","modified_gmt":"2025-01-14T14:11:55","slug":"neymar-a-linter-miami-mission-impossible","status":"publish","type":"post","link":"https:\/\/newsycanuse.com\/index.php\/2025\/01\/14\/neymar-a-linter-miami-mission-impossible\/","title":{"rendered":"Neymar \u00e0 l\u2019Inter Miami, mission impossible ?"},"content":{"rendered":"<p>Soccer <\/p>\n<div>\n<h2>Soccer L\u2019Inter Miami CF nourrit un r\u00eave : attirer la star br\u00e9silienne Neymar, dont la situation contractuelle pourrait bien l\u2019\u00e9loigner de l\u2019Arabie saoudite pour rejoindre la Major League Soccer.<\/h2>\n<p>\u00c0 quelques mois de la fin de son contrat avec Al Hilal, Neymar (32 ans) est d\u00e9sormais libre de n\u00e9gocier son avenir, et l\u2019Inter Miami semble \u00eatre l\u2019une des destinations les plus s\u00e9rieuses sur la table. Bien que le club refuse de confirmer officiellement l\u2019int\u00e9r\u00eat, les discussions en coulisses montrent clairement la volont\u00e9 de l\u2019\u00e9quipe dirig\u00e9e par Jorge Mas de faire venir la star br\u00e9silienne.<\/p>\n<h3>Un puzzle financier complexe<\/h3>\n<p>Le principal obstacle pour l\u2019Inter Miami r\u00e9side dans la question salariale. Neymar touche actuellement un salaire astronomique, estim\u00e9 \u00e0 plus de 100 millions de dollars par an, un montant bien au-del\u00e0 des capacit\u00e9s financi\u00e8res du club. Cependant, comme ce fut le cas pour Lionel Messi, l\u2019Inter Miami pourrait structurer l\u2019arriv\u00e9e de Neymar de mani\u00e8re similaire, en r\u00e9duisant une partie de son salaire et en s\u2019appuyant sur des partenariats avec des marques puissantes, comme l\u2019a fait le club avec Adidas et Apple lors de l\u2019arriv\u00e9e de Messi.<\/p>\n<h3>Le d\u00e9part de Campana, un espoir pour Neymar<\/h3>\n<p>La r\u00e9cente lib\u00e9ration de la place de joueur d\u00e9sign\u00e9 apr\u00e8s le d\u00e9part de Leonardo Campana vers le New England Revolution ouvre une voie int\u00e9ressante pour l\u2019arriv\u00e9e de Neymar. En MLS, chaque \u00e9quipe peut avoir jusqu\u2019\u00e0 trois joueurs d\u00e9sign\u00e9s, dont le salaire d\u00e9passe les limites du plafond salarial impos\u00e9 par la ligue. Actuellement, l\u2019Inter Miami ne dispose que de deux joueurs d\u00e9sign\u00e9s \u2013 Messi et Sergio Busquets \u2013 ce qui laisse un poste vacant pour un troisi\u00e8me joueur.<\/p>\n<p>Le puzzle financier semble se dessiner peu \u00e0 peu. Si la baisse notable de la valeur de Neymar rend son recrutement plus envisageable, le club devra n\u00e9anmoins jongler avec des \u00e9quilibres complexes pour respecter les r\u00e8gles de la MLS.<\/p>\n<h3>L\u2019avenir proche de Neymar : retour sur les terrains ?<\/h3>\n<p>Alors que les discussions continuent, Neymar semble \u00eatre concentr\u00e9 sur son retour au meilleur niveau. Bien qu\u2019il soit li\u00e9 \u00e0 des rumeurs concernant son avenir en MLS, le Br\u00e9silien n\u2019a pour l\u2019instant qu\u2019une seule priorit\u00e9 : retrouver la forme physique avant de participer \u00e0 la Coupe du Monde 2026 avec le Br\u00e9sil. Cependant, le r\u00eave de Jorge Mas de voir Neymar reformer le l\u00e9gendaire trio MSN (Messi, Su\u00e1rez, Neymar) \u00e0 Miami reste bien vivant.<\/p>\n<p>Si l\u2019Inter Miami parvient \u00e0 surmonter les d\u00e9fis financiers et \u00e0 convaincre Neymar de rejoindre son projet, le club pourrait bien transformer ce \u00ab\u00a0r\u00eave impossible\u00a0\u00bb en r\u00e9alit\u00e9. Mais pour l\u2019instant, selon les propos de l\u2019entra\u00eeneur Mascherano, rien n\u2019est encore acquis : <em>\u00ab\u00a0Nous n\u2019avons rien. C\u2019est un grand joueur, mais pour l\u2019instant, cela nous est impossible\u00a0\u00bb<\/em>, a-t-il d\u00e9clar\u00e9, conscient des obstacles financiers de la MLS.<\/p>\n<p>Ainsi, bien que l\u2019Inter Miami soit en pleine qu\u00eate pour recruter Neymar, la route semble sem\u00e9e d\u2019emb\u00fbches. Les mois \u00e0 venir s\u2019annoncent cruciaux pour d\u00e9terminer si la star br\u00e9silienne pourra effectivement rejoindre Messi sur la c\u00f4te Est des \u00c9tats-Unis.<\/p>\n<blockquote><p>\u2014 OneFootball (@OneFootball) <a href=\"https:\/\/twitter.com\/OneFootball\/status\/1878556199332835797?ref_src=twsrc%5Etfw\">January 12, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<p><a href=\"https:\/\/www.sport.fr\/football\/neymar-a-linter-miami-mission-impossible-1278648.shtm\" class=\"button purchase\" rel=\"nofollow noopener\" target=\"_blank\">Read More<\/a>Hugo Bernabeu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Soccer Soccer L\u2019Inter Miami CF nourrit un r\u00eave : attirer la star br\u00e9silienne Neymar, dont la situation contractuelle pourrait bien l\u2019\u00e9loigner de l\u2019Arabie saoudite pour rejoindre la Major League Soccer. \u00c0 quelques mois de la fin de son contrat avec Al Hilal, Neymar (32 ans) est d\u00e9sormais libre de n\u00e9gocier son avenir, et l\u2019Inter Miami [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":819719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[139076,30116,2005],"tags":[139075,7361],"class_list":{"0":"post-819718","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-linter","8":"category-neymar","9":"category-soccer","10":"tag-linter","11":"tag-neymar"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/posts\/819718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/comments?post=819718"}],"version-history":[{"count":0,"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/posts\/819718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/media\/819719"}],"wp:attachment":[{"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/media?parent=819718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/categories?post=819718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsycanuse.com\/index.php\/wp-json\/wp\/v2\/tags?post=819718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}